{"id":8658,"date":"2021-12-21T15:24:52","date_gmt":"2021-12-21T21:24:52","guid":{"rendered":"https:\/\/www.newsmillenium.com\/?p=8658"},"modified":"2021-12-21T15:24:56","modified_gmt":"2021-12-21T21:24:56","slug":"el-salvador-recupera-la-empleabilidad","status":"publish","type":"post","link":"https:\/\/www.newsmillenium.com\/index.php\/2021\/12\/21\/el-salvador-recupera-la-empleabilidad\/","title":{"rendered":"El Salvador recupera la empleabilidad"},"content":{"rendered":"\n<p>Seg\u00fan datos proporcionados por el ministro de Trabajo Rolando Castro el pa\u00eds pese a que atraviesa una crisis post pandemia ha logrado alcanzar en estas 2021 cifras r\u00e9cord.<\/p>\n\n\n\n<p>Para Castro se ha logrado recuperar la totalidad de los empleos que se vieron afectados durante la pandemia de la COVID-19 y se tiene un amplio super\u00e1vit.<\/p>\n\n\n\n<p>El crecimiento ha sido en 3 sectores principales del pa\u00eds: servicio:17.2%, comercio 13.4%, e industria manufacturera 5.8%, detall\u00f3 Castro.<\/p>\n\n\n\n<p>Castro destac\u00f3 que, un crecimiento arriba de 33 mil nuevos empleos nunca se hab\u00eda dado en la historia del pa\u00eds y mencion\u00f3 que esto reafirma el compromiso del Gobierno del presidente Nayib Bukele por impulsar el crecimiento econ\u00f3mico.<\/p>\n\n\n\n<p>Seg\u00fan el ministro, gracias al incremento al salario m\u00ednimo que fue aplicado a partir de agosto 2021, se tuvo un impacto positivo en la generaci\u00f3n de empleos, los salarios y el crecimiento econ\u00f3mico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan datos proporcionados por el ministro de Trabajo Rolando Castro el pa\u00eds pese a que atraviesa una crisis post pandemia ha logrado alcanzar en estas 2021 cifras r\u00e9cord. Para Castro se ha logrado recuperar la totalidad de los empleos que se vieron afectados durante la pandemia de la COVID-19 y se tiene un amplio super\u00e1vit. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8659,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-8658","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-elsalvador"},"jetpack_featured_media_url":"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2021\/12\/portyada-1-Mtrabajo1.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/8658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/comments?post=8658"}],"version-history":[{"count":1,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/8658\/revisions"}],"predecessor-version":[{"id":8660,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/8658\/revisions\/8660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media\/8659"}],"wp:attachment":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media?parent=8658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/categories?post=8658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/tags?post=8658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}