{"id":8458,"date":"2021-12-09T15:47:32","date_gmt":"2021-12-09T21:47:32","guid":{"rendered":"https:\/\/www.newsmillenium.com\/?p=8458"},"modified":"2021-12-09T15:47:34","modified_gmt":"2021-12-09T21:47:34","slug":"el-salvador-firma-el-convenio-de-suscripcion-para-incorporarse-a-caf","status":"publish","type":"post","link":"https:\/\/www.newsmillenium.com\/index.php\/2021\/12\/09\/el-salvador-firma-el-convenio-de-suscripcion-para-incorporarse-a-caf\/","title":{"rendered":"El Salvador firma el convenio de suscripci\u00f3n para incorporarse a CAF"},"content":{"rendered":"\n<p><em>La incorporaci\u00f3n de la Rep\u00fablica de El Salvador a CAF permitir\u00e1 establecer una relaci\u00f3n de beneficio mutuo mediante el <\/em><em>apoyo a la reactivaci\u00f3n y el desarrollo econ\u00f3mico inclusivo y sostenible, el acompa\u00f1amiento a los pa\u00edses de la regi\u00f3n en su transici\u00f3n hacia econom\u00edas m\u00e1s verdes e inclusivas y el fortalecimiento patrimonial de CAF para otorgar mayores recursos a los accionistas en mejores condiciones financieras; entre otros beneficios<\/em><em>.<\/em><\/p>\n\n\n\n<p>El Salvador ratific\u00f3 su intenci\u00f3n de incorporarse como pa\u00eds miembro de CAF -banco de desarrollo de Am\u00e9rica Latina- mediante la firma de un convenio para tal fin y la suscripci\u00f3n de acciones nominativas de la Serie \u201cB\u201d correspondientes al capital ordinario de CAF, el cual fue firmado por el ministro de Hacienda, <strong>Jos\u00e9 <\/strong><strong>Alejandro Zelaya<\/strong>, y el presidente ejecutivo de la instituci\u00f3n, <strong>Sergio D\u00edaz-Granados<\/strong>.<\/p>\n\n\n\n<p>\u201cPara nosotros la firma de este convenio es un honor y un gran paso porque significa una mayor dimensi\u00f3n latinoamericana y caribe\u00f1a incorporando nuevos pa\u00edses de Centroam\u00e9rica, lo cual implicar\u00e1 que CAF podr\u00e1 atender temas estrat\u00e9gicos para el pa\u00eds y el resto de la regi\u00f3n en favor de su desarrollo sostenible y la integraci\u00f3n. Este es el comienzo de un proceso que esperamos que se pueda formalizar r\u00e1pidamente, a fin de que El Salvador se incorpore a CAF y <strong>podamos trabajar de la mano en mejorar la calidad de vida de la gente<\/strong> y promover su competitividad e internacionalizaci\u00f3n\u201d, afirm\u00f3 <strong>Sergio D\u00edaz-Granados<\/strong>.<\/p>\n\n\n\n<p>Por&nbsp; su parte el titular de Hacienda, <strong>Jos\u00e9 <\/strong><strong>Alejandro Zelaya,<\/strong> agradeci\u00f3 en nombre del Gobierno del Presidente <strong>Nayib Bukele<\/strong> y el pueblo de El Salvador: \u201cla oportunidad que le dan a nuestro pueblo para seguir encaminando las pol\u00edticas de desarrollo impulsadas por el Presidente de la Rep\u00fablica, despu\u00e9s de 61 a\u00f1os, El Salvador se incorpora a un nuevo banco multilateral&#8221;, destac\u00f3.<\/p>\n\n\n\n<p>El <strong>convenio<\/strong> firmado al t\u00e9rmino de la CLXXIII sesi\u00f3n del Directorio de CAF, realizado en Cartagena de Indias, <strong>define los pasos a seguir para la plena incorporaci\u00f3n de El Salvador como miembro de CAF<\/strong>. Entre los beneficios que recibir\u00e1 el pa\u00eds centroamericano estar\u00e1 el acceso a nuevas fuentes de financiamiento, a recursos de asistencia t\u00e9cnica y a conocimiento especializado que mejorar\u00e1 el bienestar de la poblaci\u00f3n y la competitividad e inserci\u00f3n internacional del pa\u00eds.<\/p>\n\n\n\n<p>CAF es una instituci\u00f3n financiera multilateral cuya misi\u00f3n es apoyar el desarrollo sostenible de sus pa\u00edses accionistas y la integraci\u00f3n de Am\u00e9rica Latina. Sus accionistas son: <strong>Argentina, Barbados, Bolivia, Brasil, Chile, Colombia, Costa Rica, Ecuador, Espa\u00f1a, Jamaica, M\u00e9xico, Panam\u00e1, Paraguay, Per\u00fa, Portugal, Rep\u00fablica Dominicana, Trinidad y Tobago, Uruguay, Venezuela y 13 bancos privados de la regi\u00f3n. <\/strong>Atiende a los sectores p\u00fablico y privado, suministrando productos y servicios m\u00faltiples a una amplia cartera de clientes constituida por los Estados accionistas, empresas privadas e instituciones financieras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La incorporaci\u00f3n de la Rep\u00fablica de El Salvador a CAF permitir\u00e1 establecer una relaci\u00f3n de beneficio mutuo mediante el apoyo a la reactivaci\u00f3n y el desarrollo econ\u00f3mico inclusivo y sostenible, el acompa\u00f1amiento a los pa\u00edses de la regi\u00f3n en su transici\u00f3n hacia econom\u00edas m\u00e1s verdes e inclusivas y el fortalecimiento patrimonial de CAF para otorgar [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8459,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-8458","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-elsalvador"},"jetpack_featured_media_url":"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2021\/12\/portada-2-hacienda-espana-scaled.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/8458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/comments?post=8458"}],"version-history":[{"count":1,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/8458\/revisions"}],"predecessor-version":[{"id":8460,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/8458\/revisions\/8460"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media\/8459"}],"wp:attachment":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media?parent=8458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/categories?post=8458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/tags?post=8458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}