{"id":8025,"date":"2021-11-12T08:15:22","date_gmt":"2021-11-12T14:15:22","guid":{"rendered":"https:\/\/www.newsmillenium.com\/?p=8025"},"modified":"2021-11-12T08:15:24","modified_gmt":"2021-11-12T14:15:24","slug":"que-es-el-dia-del-soltero-y-por-que-rompe-records-de-ventas-en-el-mundo","status":"publish","type":"post","link":"https:\/\/www.newsmillenium.com\/index.php\/2021\/11\/12\/que-es-el-dia-del-soltero-y-por-que-rompe-records-de-ventas-en-el-mundo\/","title":{"rendered":"Qu\u00e9 es el D\u00eda del Soltero y por qu\u00e9 rompe r\u00e9cords de ventas en el mundo"},"content":{"rendered":"\n<p>Millones de personas sin pareja festejaron este 11 de noviembre el D\u00eda del soltero, celebraci\u00f3n de origen chino y que se ha extendido mundialmente durante los \u00faltimos a\u00f1os, a pesar de que a\u00fan existen dudas sobre qu\u00e9 es y porqu\u00e9 es un fen\u00f3meno global de ventas online.<\/p>\n\n\n\n<p>El D\u00eda del soltero, o Doble 11, fue creado originalmente por estudiantes universitarios de China a inicios de la d\u00e9cada de los 90 como una especie de protesta contra el D\u00eda de San Valent\u00edn. Se festeja cada 11 de noviembre debido a que en China el n\u00famero 1 tambi\u00e9n significa una persona sola.<\/p>\n\n\n\n<p>Esta fecha tiene como prop\u00f3sito exaltar el orgullo de ser soltero y relajar un poco los niveles de estr\u00e9s de la sociedad china en la que el compromiso es una parte fundamental de su l\u00ednea de vida, especialmente, para los hombres.<\/p>\n\n\n\n<p>A pesar de no ser un d\u00eda festivo oficial, el D\u00eda del soltero se festeja en todo el pa\u00eds asi\u00e1tico. En esta fecha, los solteros acostumbran autoregalarse obsequios, comidas, o viajes para convivir con ellos mismos.<\/p>\n\n\n\n<p>No obstante, esta celebraci\u00f3n ha mutado desde la \u00faltima d\u00e9cada y se ha convertido en uno de los mayores fen\u00f3menos de ventas online a nivel mundial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Millones de personas sin pareja festejaron este 11 de noviembre el D\u00eda del soltero, celebraci\u00f3n de origen chino y que se ha extendido mundialmente durante los \u00faltimos a\u00f1os, a pesar de que a\u00fan existen dudas sobre qu\u00e9 es y porqu\u00e9 es un fen\u00f3meno global de ventas online. El D\u00eda del soltero, o Doble 11, fue [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8026,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[2,1],"tags":[],"class_list":{"0":"post-8025","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-featured","8":"category-uncategorized"},"jetpack_featured_media_url":"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2021\/11\/portada-1-dia-del-soltero.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/8025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/comments?post=8025"}],"version-history":[{"count":1,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/8025\/revisions"}],"predecessor-version":[{"id":8027,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/8025\/revisions\/8027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media\/8026"}],"wp:attachment":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media?parent=8025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/categories?post=8025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/tags?post=8025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}