{"id":6040,"date":"2021-07-28T10:57:04","date_gmt":"2021-07-28T16:57:04","guid":{"rendered":"https:\/\/www.newsmillenium.com\/?p=6040"},"modified":"2021-07-28T10:57:09","modified_gmt":"2021-07-28T16:57:09","slug":"ocho-anos-de-la-organizacion-por-la-paz-hwpl-afiliada-a-la-onu","status":"publish","type":"post","link":"https:\/\/www.newsmillenium.com\/index.php\/2021\/07\/28\/ocho-anos-de-la-organizacion-por-la-paz-hwpl-afiliada-a-la-onu\/","title":{"rendered":"Ocho A\u00f1os de la Organizaci\u00f3n por la Paz HWPL afiliada a la ONU"},"content":{"rendered":"\n<p><strong>* Se ha publicado un n\u00famero especial en ingl\u00e9s de la historia verdadera de la paz.<\/strong><\/p>\n\n\n\n<p>Un n\u00famero especial que contiene el movimiento por la paz y la evidencia de los \u00faltimos ocho a\u00f1os de HWPL, una organizaci\u00f3n internacional para la paz asociada con el Departamento de Comunicaciones Globales de las Naciones Unidas (DGC) y el Consejo Econ\u00f3mico y Social (ECOSOC), fue publicado por primera vez en ingl\u00e9s el 10 de julio.<\/p>\n\n\n\n<p>Despu\u00e9s de que un n\u00famero especial de 64 p\u00e1ginas titulado &lt;Coreano, Man Hee Lee, La Historia Verdadera de la Paz&gt; se publicara en mayo a trav\u00e9s de Cheonji Ilbo, un peri\u00f3dico diario de Corea, la serie comenz\u00f3 en ingl\u00e9s a petici\u00f3n de los lectores.<\/p>\n\n\n\n<p><strong>* Los contenidos principales e intenciones de planificaci\u00f3n del n\u00famero especial de la historia verdadera de la paz.<\/strong><\/p>\n\n\n\n<p>El n\u00famero especial se enfoca principalmente en los logros del movimiento por la paz del presidente Man Hee Lee de HWPL. Ofrece una introducci\u00f3n detallada sobre el Acuerdo de Paz de Mindanao en Filipinas; los antecedentes de la proclamaci\u00f3n de la Declaraci\u00f3n de Paz y Cese de Guerras (DPCW) que est\u00e1 compuesto de 10 art\u00edculos y 38 cl\u00e1usulas para la paz sostenible en la comunidad internacional; y \u2018la carta de apoyo del DPCW\u2019 del Parlamento Pan-Africano (PAP).<\/p>\n\n\n\n<p>A la misma vez, presenta a los mensajeros de la paz en la comunidad global, que trabajan con HWPL para liderar el logro de la paz mundial. Un funcionario de Cheonji Ilbo destac\u00f3 que es \u201cuna fuente clave para la paz mundial\u201d. Tambi\u00e9n dijo: \u201cAl ver las noticias del movimiento por la paz del presidente Man Hee Lee, espero que se unan para lograr una paz sostenible&#8221;.<\/p>\n\n\n\n<p><strong>* Los movimientos por la paz del presidente Man Hee Lee de HWPL<\/strong><\/p>\n\n\n\n<p>El Sr. Man Hee Lee, presidente de HWPL, trabaja internacionalmente para &#8220;el cese de la guerra&#8221;, \u00e9l es un veterano de la Guerra de Corea y sufri\u00f3 de la devastaci\u00f3n de la guerra. Lamenta la muerte de j\u00f3venes inocentes que murieron en la guerra y est\u00e1 activamente involucrado en actividades para hacer realidad el derecho internacional de paz y armon\u00eda entre religiones. A pesar de estar en una edad avanzada -90 a\u00f1os este a\u00f1o-, continua el movimiento por la paz y emiti\u00f3 la &#8220;Declaraci\u00f3n de HWPL sobre la crisis de derechos humanos en Myanmar&#8221; en abril de 2021. Hasta ahora, ha visitado 49 pa\u00edses a trav\u00e9s de 31 Giras Mundiales para despertar un sentido de paz en la comunidad global.<\/p>\n\n\n\n<p><strong>* Gu\u00eda para leer art\u00edculos en la versi\u00f3n en ingl\u00e9s.<\/strong><\/p>\n\n\n\n<p>El tema del primer art\u00edculo en ingl\u00e9s del n\u00famero especial es la historia de un acuerdo de paz civil guiado en el 2014 en Mindanao, Filipinas, una regi\u00f3n que sufri\u00f3 el sangriento conflicto cat\u00f3lico-isl\u00e1mico que dur\u00f3 40 a\u00f1os y mat\u00f3 a 120.000 personas. El presidente Lee, quien dirigi\u00f3 este acuerdo, fue reconocido por la comunidad internacional. Los art\u00edculos relacionados se pueden encontrar en el enlace incluido&nbsp;abajo, y se subir\u00e1n peri\u00f3dicamente en el futuro.<\/p>\n\n\n\n<p><strong>Serie especial: La historia verdadera de la paz, N\u00famero Especial #1<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.hwpl.kr\/upload\/ebook\/peace_special\/en\/peace_special_1_1.html\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>* Se ha publicado un n\u00famero especial en ingl\u00e9s de la historia verdadera de la paz. Un n\u00famero especial que contiene el movimiento por la paz y la evidencia de los \u00faltimos ocho a\u00f1os de HWPL, una organizaci\u00f3n internacional para la paz asociada con el Departamento de Comunicaciones Globales de las Naciones Unidas (DGC) y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6041,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[14,10],"tags":[],"class_list":{"0":"post-6040","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destacads","8":"category-opinion"},"jetpack_featured_media_url":"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2021\/07\/portada-1-jovenes-por-la-paz.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/6040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/comments?post=6040"}],"version-history":[{"count":1,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/6040\/revisions"}],"predecessor-version":[{"id":6042,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/6040\/revisions\/6042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media\/6041"}],"wp:attachment":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media?parent=6040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/categories?post=6040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/tags?post=6040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}