{"id":5462,"date":"2021-06-16T07:37:10","date_gmt":"2021-06-16T13:37:10","guid":{"rendered":"https:\/\/www.newsmillenium.com\/?p=5462"},"modified":"2021-06-16T07:37:14","modified_gmt":"2021-06-16T13:37:14","slug":"gobierno-entrega-sillas-de-ruedas-a-personas-con-discapacidad","status":"publish","type":"post","link":"https:\/\/www.newsmillenium.com\/index.php\/2021\/06\/16\/gobierno-entrega-sillas-de-ruedas-a-personas-con-discapacidad\/","title":{"rendered":"Gobierno entrega sillas de ruedas  a personas con discapacidad"},"content":{"rendered":"\n<p>El Gobierno del Presidente Nayib Bukele, a trav\u00e9s del Fondo de Protecci\u00f3n de Lisiados y Discapacitados a Consecuencia del Conflicto Armado (FOPROLYD), entreg\u00f3 hoy 26 sillas de ruedas para igual n\u00famero de personas con discapacidad.<\/p>\n\n\n\n<p>Estos beneficiados son familiares de miembros del FOPROLYD, instituci\u00f3n aut\u00f3noma del Gobierno responsable de la atenci\u00f3n y seguimiento del proceso de rehabilitaci\u00f3n, reinserci\u00f3n productiva, del otorgamiento oportuno de las prestaciones econ\u00f3micas y de especies de personas que resultaron lesionadas y con discapacidad a consecuencia del conflicto armado.<\/p>\n\n\n\n<p>El presidente de la junta directiva de FOPROLYD, Rafael Aguill\u00f3n Rivera, destac\u00f3 que esta ayuda llega mediante la gesti\u00f3n de esta instituci\u00f3n con la Asociaci\u00f3n Cristiana de las Buenas Nuevas, y fue posible luego de tomar en cuenta criterios m\u00e9dicos a cargo de un equipo multidisciplinario que realiz\u00f3 evaluaciones de campo en visitas a las casas de los solicitantes, lo que deriv\u00f3, adem\u00e1s, en la adecuaci\u00f3n personalizada de cada una de las sillas de ruedas.<\/p>\n\n\n\n<p>Aguill\u00f3n Rivera dijo que esta entrega forma parte del trabajo que realiza FOPROLYD siguiendo instrucciones del Presidente Bukele de llevar alivio al pueblo salvadore\u00f1o. \u201cSon 26 personas del \u00e1rea de San Salvador que necesitan de una mano amiga, en este caso, una silla de ruedas\u201d, agreg\u00f3.<\/p>\n\n\n\n<p>FORPOLYD brinda atenci\u00f3n a m\u00e1s de 19,000 personas, provenientes de tres grupos afectados por el conflicto armado: poblaci\u00f3n civil, lisiados del Frente Farabundo Mart\u00ed para la Liberaci\u00f3n Nacional (FMLN) y de la Fuerza Armada de El Salvador (FAES).<\/p>\n\n\n\n<p>A trav\u00e9s de este fondo, el Gobierno lleva a cabo diversos programas como otorgamiento de cr\u00e9ditos a bajos intereses, proyectos productivos de reinserci\u00f3n social, brigadas m\u00e9dicas odontol\u00f3gicas, asesoramientos jur\u00eddicos, entregas de sillas de ruedas, muletas, bastones y lentes para la lectura.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large td-caption-align-https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2021\/06\/portada-1-silla-de-ruedas-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2021\/06\/portada-1-silla-de-ruedas-1024x683.jpg\" alt=\"\" class=\"wp-image-5464\" srcset=\"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2021\/06\/portada-1-silla-de-ruedas-1024x683.jpg 1024w, https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2021\/06\/portada-1-silla-de-ruedas-300x200.jpg 300w, https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2021\/06\/portada-1-silla-de-ruedas-768x512.jpg 768w, https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2021\/06\/portada-1-silla-de-ruedas-1536x1024.jpg 1536w, https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2021\/06\/portada-1-silla-de-ruedas-2048x1365.jpg 2048w, https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2021\/06\/portada-1-silla-de-ruedas-696x464.jpg 696w, https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2021\/06\/portada-1-silla-de-ruedas-1068x712.jpg 1068w, https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2021\/06\/portada-1-silla-de-ruedas-1920x1280.jpg 1920w, https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2021\/06\/portada-1-silla-de-ruedas-630x420.jpg 630w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno del Presidente Nayib Bukele, a trav\u00e9s del Fondo de Protecci\u00f3n de Lisiados y Discapacitados a Consecuencia del Conflicto Armado (FOPROLYD), entreg\u00f3 hoy 26 sillas de ruedas para igual n\u00famero de personas con discapacidad. Estos beneficiados son familiares de miembros del FOPROLYD, instituci\u00f3n aut\u00f3noma del Gobierno responsable de la atenci\u00f3n y seguimiento del proceso [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5463,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[4,1],"tags":[],"class_list":{"0":"post-5462","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-elsalvador","8":"category-uncategorized"},"jetpack_featured_media_url":"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2021\/06\/portada-2-silla-de-ruedas-scaled.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/5462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/comments?post=5462"}],"version-history":[{"count":1,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/5462\/revisions"}],"predecessor-version":[{"id":5465,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/5462\/revisions\/5465"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media\/5463"}],"wp:attachment":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media?parent=5462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/categories?post=5462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/tags?post=5462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}