{"id":26290,"date":"2026-01-15T07:41:58","date_gmt":"2026-01-15T13:41:58","guid":{"rendered":"https:\/\/www.newsmillenium.com\/?p=26290"},"modified":"2026-01-15T07:42:00","modified_gmt":"2026-01-15T13:42:00","slug":"el-contenido-generado-con-ia-esta-acaparando-youtube","status":"publish","type":"post","link":"https:\/\/www.newsmillenium.com\/index.php\/2026\/01\/15\/el-contenido-generado-con-ia-esta-acaparando-youtube\/","title":{"rendered":"El contenido generado con IA est\u00e1 acaparando YouTube"},"content":{"rendered":"\n<p>NotiPress<\/p>\n\n\n\n<p>Hasta un tercio de videos en YouTube Shorts est\u00e1 compuesto por inteligencia artificial de baja calidad, conocido como &#8220;AI Slop&#8221;, revel\u00f3 un estudio de plataforma de edici\u00f3n Kapwing. El an\u00e1lisis sugiere que esta tendencia no solo perjudica a creadores humanos, sino que altera la experiencia de los usuarios y genera ingresos millonarios para los responsables de este tipo de contenido.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>En su investigaci\u00f3n, Kapwing identific\u00f3 que el 33% del contenido sugerido a nuevos usuarios en YouTube Shorts corresponde a lo cual se clasifica como AI Slop o su variante &#8220;Brainrot&#8221;, ambos dise\u00f1ados para maximizar vistas sin aportar valor creativo. Para ello, se cre\u00f3 una cuenta nueva en la plataforma, sin historial de navegaci\u00f3n, y se analizaron los primeros 500 videos recibidos en el feed. De ellos, 104 \u2014el 21%\u2014 fueron categorizados como Slop de IA.<br>&#8220;YouTube est\u00e1 bombardeando a los nuevos usuarios con videos generados por IA, y si hay filtros implementados, no est\u00e1n detectando una cantidad masiva&#8221;, explic\u00f3 Taylor Tomita, especialista senior de Kapwing, en entrevista con WIRED en Espa\u00f1ol.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La investigaci\u00f3n incluy\u00f3 tambi\u00e9n el an\u00e1lisis de los 100 canales m\u00e1s vistos en YouTube en distintos pa\u00edses. En Pakist\u00e1n, 20 de estos canales producen exclusivamente AI Slop, lo cual representa el mayor porcentaje global en esta categor\u00eda. Seg\u00fan Tomita, &#8220;el aumento del Slop de IA es ciertamente un fen\u00f3meno global, pero Pakist\u00e1n tiene el mayor n\u00famero de canales que producen Slop de IA en su top 100&#8221;.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Este contenido, definido en el informe como &#8220;descuidado y de baja calidad, generado mediante aplicaciones autom\u00e1ticas y distribuido para farmear vistas o influir en opiniones pol\u00edticas&#8221;, ha demostrado ser altamente rentable. Por ejemplo, el canal Bandar Apna Dost, de India, acumula m\u00e1s de 2 mil millones de vistas y genera aproximadamente 4.25 millones de d\u00f3lares anuales en ingresos publicitarios. En Estados Unidos, Cuentos Facinantes lidera con casi seis millones de suscriptores y contenido automatizado inspirado en franquicias populares como Dragon Ball.<\/p>\n\n\n\n<p>Espa\u00f1a destaca como el pa\u00eds con mayor n\u00famero de suscriptores en canales de este tipo, alcanzando los 20.2 millones. El canal Imperio de Jes\u00fas, con versiones digitales de figuras religiosas en escenarios absurdos, ejemplifica esta tendencia.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>El reporte plantea que la abundancia de este contenido afecta la visibilidad de propuestas originales y tiene posibles consecuencias psicol\u00f3gicas, ya que la exposici\u00f3n constante a videos automatizados puede distorsionar la percepci\u00f3n de la realidad. El investigador Eryk Salvaggio se\u00f1al\u00f3 que esta saturaci\u00f3n refleja &#8220;una dependencia humana excesiva de los filtros algor\u00edtmicos para clasificar el mundo&#8221;.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Mientras YouTube defiende el uso de IA como una herramienta democratizadora, el informe advierte que los incentivos actuales favorecen la cantidad por encima de la calidad. Frente a esta problem\u00e1tica, la alfabetizaci\u00f3n medi\u00e1tica se presenta como una respuesta clave para que los usuarios desarrollen criterios m\u00e1s s\u00f3lidos ante la sobresaturaci\u00f3n de contenido visual automatizado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NotiPress Hasta un tercio de videos en YouTube Shorts est\u00e1 compuesto por inteligencia artificial de baja calidad, conocido como &#8220;AI Slop&#8221;, revel\u00f3 un estudio de plataforma de edici\u00f3n Kapwing. El an\u00e1lisis sugiere que esta tendencia no solo perjudica a creadores humanos, sino que altera la experiencia de los usuarios y genera ingresos millonarios para los [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":26291,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[14,3],"tags":[],"class_list":{"0":"post-26290","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destacads","8":"category-internacional"},"jetpack_featured_media_url":"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2026\/01\/portada-1-AI-slop.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/26290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/comments?post=26290"}],"version-history":[{"count":1,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/26290\/revisions"}],"predecessor-version":[{"id":26292,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/26290\/revisions\/26292"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media\/26291"}],"wp:attachment":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media?parent=26290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/categories?post=26290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/tags?post=26290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}