{"id":21876,"date":"2024-09-04T07:38:01","date_gmt":"2024-09-04T13:38:01","guid":{"rendered":"https:\/\/www.newsmillenium.com\/?p=21876"},"modified":"2024-09-04T07:38:04","modified_gmt":"2024-09-04T13:38:04","slug":"estafadores-de-cajeros-automaticos-de-bitcoin-robaron-65-millones-de-dolares","status":"publish","type":"post","link":"https:\/\/www.newsmillenium.com\/index.php\/2024\/09\/04\/estafadores-de-cajeros-automaticos-de-bitcoin-robaron-65-millones-de-dolares\/","title":{"rendered":"Estafadores de cajeros autom\u00e1ticos de bitcoin robaron 65 millones de d\u00f3lares"},"content":{"rendered":"\n<p>NotiPress<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Las estafas son una materia que avanza a la par de los nuevos medios tecnol\u00f3gicos. Una vez que los robos a trav\u00e9s de los giros postales o las tarjetas de regalo fueron descubiertas, los estafadores optaron por el mundo cripto, particularmente por bitcoin. En un informe, la Comisi\u00f3n Federal de Comercio (FDC) de Estados Unidos se\u00f1al\u00f3 que la cantidad de dinero perdido en las estafas de los cajeros autom\u00e1ticos de bitcoin aument\u00f3 casi 10 veces entre 2020 y 2023, pasando de 12 millones de d\u00f3lares a 114 millones. En a\u00f1o 2024, los consumidores ya perdieron 65 millones de d\u00f3lares por este tipo de estafa.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>A pesar de cambiar los medios, las modalidades de estafa siguen siendo las mismas. Por lo general, se tratan de esquemas que enga\u00f1an a las v\u00edctimas para que paguen a los estafadores mediante transferencias bancarias, compras de tarjetas de regalo o hasta una pila de efectivo, por ejemplo, en una caja de zapatos. Pero, ahora se le suma la estafa por cajero autom\u00e1tico de bitcoin.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Estas m\u00e1quinas f\u00edsicas pueden utilizarse para comprar o vender criptomonedas en lugares como gasolineras y supermercados. Los estafadores, para llevar a cabo su plan, primero llaman por tel\u00e9fono o le env\u00edan un mensaje a la v\u00edctima. Luego se hacen pasar por un funcionario bancario o gubernamental para convencer a la v\u00edctima de que su cuenta bancaria fue vulnerada y que debe tomar medidas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Despu\u00e9s, le indican que saquen una gran suma de dinero en efectivo y la depositen en un cajero autom\u00e1tico de Bitcoin para mantener sus fondos seguros. Una vez en el cajero autom\u00e1tico de Bitcoin, los estafadores le env\u00edan a su v\u00edctima un c\u00f3digo QR para escanear en la m\u00e1quina. Autom\u00e1ticamente, todo el efectivo de la v\u00edctima pasa a la billetera de criptomonedas del estafador.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>En 2024, las v\u00edctimas aseguraron haber perdido alrededor de 10 mil d\u00f3lares en estafas con cajeros de bitcoin. Algunos estados norteamericanos como Vermont o Minnesota han tomado medidas para detener este esquema promulgando leyes que imponen l\u00edmites diarios a las transacciones en los quioscos de criptomonedas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Para evitar caer en este tipo de estafas, las autoridades recomiendan verificar los correos electr\u00f3nicos o las llamadas telef\u00f3nicas que reciben de una supuesta empresa o instituci\u00f3n financiera para comprobar su legitimidad. Adem\u00e1s, advierten que nunca debe retirarse dinero siguiendo instrucciones de una interacci\u00f3n aleatoria.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Al igual que esta tendencia, hay otras estafas de criptomonedas en aumento. Entre ellas, las estafas de criptomonedas deepfake en YouTube, actores que se hacen pasar por periodistas para vaciar las billeteras digitales de las v\u00edctimas, como tambi\u00e9n estafas de &#8220;matanza de cerdos&#8221; las cuales llevaron al arresto de un exdirector ejecutivo de un banco que rob\u00f3 millones para invertir en un esquema de criptomonedas falso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NotiPress Las estafas son una materia que avanza a la par de los nuevos medios tecnol\u00f3gicos. Una vez que los robos a trav\u00e9s de los giros postales o las tarjetas de regalo fueron descubiertas, los estafadores optaron por el mundo cripto, particularmente por bitcoin. En un informe, la Comisi\u00f3n Federal de Comercio (FDC) de Estados [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21877,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[14,3],"tags":[],"class_list":{"0":"post-21876","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destacads","8":"category-internacional"},"jetpack_featured_media_url":"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2024\/09\/portada-1-cajeros-bitcoin.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/21876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/comments?post=21876"}],"version-history":[{"count":1,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/21876\/revisions"}],"predecessor-version":[{"id":21878,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/21876\/revisions\/21878"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media\/21877"}],"wp:attachment":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media?parent=21876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/categories?post=21876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/tags?post=21876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}