{"id":20763,"date":"2024-06-14T07:49:10","date_gmt":"2024-06-14T13:49:10","guid":{"rendered":"https:\/\/www.newsmillenium.com\/?p=20763"},"modified":"2024-06-14T07:49:14","modified_gmt":"2024-06-14T13:49:14","slug":"la-lnb-se-une-a-la-fiesta-deportiva-a-traves-de-los-sorteos-dedicados-al-mes-del-deporte","status":"publish","type":"post","link":"https:\/\/www.newsmillenium.com\/index.php\/2024\/06\/14\/la-lnb-se-une-a-la-fiesta-deportiva-a-traves-de-los-sorteos-dedicados-al-mes-del-deporte\/","title":{"rendered":"La LNB se une a la fiesta deportiva a trav\u00e9s de los sorteos dedicados al Mes del Deporte"},"content":{"rendered":"\n<p>El presidente ad hon\u00f3rem del Instituto Nacional de los Deportes de El Salvador (INDES), Yamil Bukele, junto al director presidente de la Loter\u00eda Nacional de Beneficencia de El Salvador (LNB), Javier Mili\u00e1n, anunciaron que los sorteos correspondientes a junio se har\u00e1n en conmemoraci\u00f3n del Mes del Deporte, por tercer a\u00f1o consecutivo.<\/p>\n\n\n\n<p>Este homenaje al deporte por parte de Loter\u00eda coincide con el 43\u00b0 aniversario del INDES, que en los \u00faltimos cinco a\u00f1os se ha dedicado a promover en un 100 por ciento la pr\u00e1ctica deportiva en sus m\u00e1s de 50 disciplinas en actividad.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La celebraci\u00f3n incluye la dedicatoria de todos los Mi\u00e9rcoles de Alegr\u00eda del mes. El primero fue el 5 de junio, dedicado a la Liga de F\u00fatbol Playa (LFP) y que regal\u00f3 un primer premio de $175,000 entre muchos m\u00e1s. El segundo sorteo se llev\u00f3 a cabo esta semana en las instalaciones del foro de la Loter\u00eda y fue en honor al Programa de Actividad F\u00edsica para el Adulto Mayor M\u00e1s 60; para este sorteo se regal\u00f3 un primer premio de $205,000.<\/p>\n\n\n\n<p>Para el pr\u00f3ximo 19 de junio se homenajear\u00e1 a la Liga Nacional de F\u00fatbol (LNF). En el cuarto y \u00faltimo sorteo ser\u00e1 el turno de LaLiga, Valores y Oportunidad. Cada uno de estos sorteos tendr\u00e1n un bols\u00f3n de premios de m\u00e1s de $672,000 repartidos en m\u00e1s de 12,000 oportunidades de ganar.<\/p>\n\n\n\n<p>Sobre la alianza que se ha creado entre el INDES y la LNB, el presidente del instituto de los deportes, Yamil Bukele, expres\u00f3 su profundo agradecimiento por el respaldo que recibe por parte de las autoridades de dicha instituci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"322\" src=\"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2024\/06\/portada-1-2-indes-lnb.jpg\" alt=\"\" class=\"wp-image-20765\" srcset=\"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2024\/06\/portada-1-2-indes-lnb.jpg 550w, https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2024\/06\/portada-1-2-indes-lnb-300x176.jpg 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/figure>\n\n\n\n<p>\u201cQueremos agradecer al presidente de la LNB, Javier Mili\u00e1n, por confiar en el deporte y recalco, no es confiar en el INDES, es apostarle a todos los atletas salvadore\u00f1os que hoy nos acompa\u00f1an en este lanzamiento y que son nuestra raz\u00f3n de ser\u201d, dijo el presidente del INDES.<\/p>\n\n\n\n<p>El jefe del INDES agreg\u00f3 que el trabajo que se est\u00e1 ejecutando por parte de ambas instituciones es fundamental para que los atletas salvadore\u00f1os puedan contar lo necesario para sus competencias y preparaci\u00f3n.<\/p>\n\n\n\n<p>\u201cSiempre el deporte requiere m\u00e1s y los atletas necesitan de ese apoyo, es por eso que como instituci\u00f3n estamos agradecidos con la loter\u00eda por ese respaldo econ\u00f3mico y en el desarrollo de eventos deportivos\u201d, dijo Yamil Bukele.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Eso s\u00ed, el funcionario agradeci\u00f3 el gran apoyo que se tiene por parte del personal de ambas instituciones para la organizaci\u00f3n de cada actividad.<\/p>\n\n\n\n<p>\u201cSin el trabajo interinstitucional que se realiza por parte de ambas entidades, del personal de la LNB y del INDES, no se podr\u00edan ejecutar estos eventos, as\u00ed como los logros y avances no ser\u00edan una realidad y satisfactorios. No es f\u00e1cil hacer deporte en nuestro pa\u00eds por la historia en la que se hab\u00eda manejado en el pa\u00eds\u201d, dijo Bukele.<\/p>\n\n\n\n<p>Cabe recalcar que tambi\u00e9n se dedicar\u00e1 un Lot\u00edn especial al Mes del Deporte, el cual tendr\u00e1 un costo de $1 y estar\u00e1 a la venta a partir del 12 de junio. Esta edici\u00f3n de Lot\u00edn entregar\u00e1 m\u00e1s de $160,000 en premios.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Para el presidente de la LNB, Javier Mili\u00e1n, el ser parte del trabajo que est\u00e1 realizando INDES, es una forma de aportar al deporte de El Salvador, algo de lo que se siente orgulloso.<\/p>\n\n\n\n<p>\u201cEs un orgullo para nosotros como instituci\u00f3n el poder participar y ser parte de la historia deportiva como la est\u00e1n construyendo las autoridades del INDES. Sin duda alguna para cada uno de los miembros de la loter\u00eda es importante estar presente en actividades deportivas, respaldando de esa manera a los atletas de nuestro pa\u00eds\u201d, coment\u00f3 Mili\u00e1n.<\/p>\n\n\n\n<p>Tambi\u00e9n asegur\u00f3 que como instituci\u00f3n p\u00fablica, est\u00e1n dispuestos a trabajar de la mano con el INDES en pro del deporte y los atletas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u201cComo Loter\u00eda Nacional de Beneficencia estamos ac\u00e1 presentes para apoyar al deporte nacional, nos sumamos a este esfuerzo y es por eso que el mes de junio los sorteos est\u00e1n dedicados a diferentes proyectos que el INDES est\u00e1 ejecutando y que son un \u00e9xito\u201d, dijo Mili\u00e1n.<\/p>\n\n\n\n<p>Aparte de los sorteos, tambi\u00e9n se han programado actividades deportivas en diferentes lugares. Para el 15 y 16 de junio est\u00e1 agendada la I Parada Evento Loter\u00eda Plaza Merliot, torneo de baloncesto 3&#215;3. Los encuentros comenzar\u00e1n a partir de las 8:00 de la ma\u00f1ana hasta las 5:00 de la tarde y los equipos ganadores recibir\u00e1n un premio en efectivo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>En esa misma l\u00ednea, el s\u00e1bado 22 de junio se desarrollar\u00e1 el evento del Hombre y la Mujer M\u00e1s Fuerte. Esta actividad est\u00e1 programada para realizarse en el Estadio de Deportes de Playa, ubicado en el Complejo Deportivo Flor Blanca, a partir de las 7:00 a.m.<\/p>\n\n\n\n<p>Las actividades conmemorativas al Mes del Deporte incluir\u00e1n la proyecci\u00f3n del documental #EsM\u00e1gico, el 29 de junio en San Miguel y el 30, en Santa Ana, ambos eventos se llevar\u00e1n a cabo en Metrocentro.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Y finalizaremos todas las actividades de esta celebraci\u00f3n, con la transmisi\u00f3n de la final de la Eurocopa y la Copa Am\u00e9rica el 14 de julio.<\/p>\n\n\n\n<p>En 2022, los sorteos de Loter\u00eda estuvieron dedicados a los escenarios deportivos, el deporte inclusivo y los atletas \u00e9lite del pa\u00eds, entre otros. Para 2023, la Loter\u00eda tambi\u00e9n homenaje\u00f3 a los XXIV Juegos Centroamericanos y del Caribe San Salvador 2023 y a su Programa de Voluntariado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente ad hon\u00f3rem del Instituto Nacional de los Deportes de El Salvador (INDES), Yamil Bukele, junto al director presidente de la Loter\u00eda Nacional de Beneficencia de El Salvador (LNB), Javier Mili\u00e1n, anunciaron que los sorteos correspondientes a junio se har\u00e1n en conmemoraci\u00f3n del Mes del Deporte, por tercer a\u00f1o consecutivo. Este homenaje al deporte [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20764,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[5],"tags":[],"class_list":{"0":"post-20763","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deportes"},"jetpack_featured_media_url":"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2024\/06\/portada-1-indes-lnb.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/20763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/comments?post=20763"}],"version-history":[{"count":1,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/20763\/revisions"}],"predecessor-version":[{"id":20766,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/20763\/revisions\/20766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media\/20764"}],"wp:attachment":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media?parent=20763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/categories?post=20763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/tags?post=20763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}