{"id":1995,"date":"2020-08-25T13:45:22","date_gmt":"2020-08-25T19:45:22","guid":{"rendered":"https:\/\/www.newsmillenium.com\/?p=1995"},"modified":"2020-08-25T13:45:40","modified_gmt":"2020-08-25T19:45:40","slug":"microsoft-anuncia-la-fecha-del-fin-de-explorer","status":"publish","type":"post","link":"https:\/\/www.newsmillenium.com\/index.php\/2020\/08\/25\/microsoft-anuncia-la-fecha-del-fin-de-explorer\/","title":{"rendered":"Microsoft anuncia la fecha del fin de Explorer"},"content":{"rendered":"\n<p>El fin de\nuna era en la navegaci\u00f3n de internet llegar el 17 de agosto del pr\u00f3ximo a\u00f1o;\nMicrosoft reconoce que es un \u2018paso dif\u00edcil\u2019.<\/p>\n\n\n\n<p>Microsoft\nanunci\u00f3 que dejar\u00e1 de darle mantenimiento a Internet Explorer, es decir, que\ndejar\u00e1 de funcionar a partir del 17 de agosto de 2021.<\/p>\n\n\n\n<p>En su\nblog, la compa\u00f1\u00eda tecnol\u00f3gica especific\u00f3 que \u201csi bien sabemos que este cambio\nser\u00e1 dif\u00edcil para algunos clientes, creemos que los clientes aprovechar\u00e1n al\nm\u00e1ximo Microsoft 365 cuando utilicen el nuevo Microsoft Edge (reemplazo del\nExplorer). Estamos comprometidos a ayudar a que esta transici\u00f3n sea lo m\u00e1s\nfluida posible\u201d.<\/p>\n\n\n\n<p>Microsoft\nadmiti\u00f3 que \u201clos clientes han estado usando Internet Explorer 11 desde 2013,\ncuando el entorno en l\u00ednea era mucho menos sofisticado que el panorama actual.\nDesde entonces, los est\u00e1ndares web abiertos y los navegadores m\u00e1s nuevos, como\nel nuevo Microsoft Edge, han permitido experiencias en l\u00ednea mejores y m\u00e1s\ninnovadoras\u201d.<\/p>\n\n\n\n<p>El\nInternet Explorer fue lanzado en 1995 y fue considerado como uno de los\nnavegadores web m\u00e1s utilizados de Internet desde 1999, con un cl\u00edmax de\nutilizaci\u00f3n del 95 % entre 2002 y 2003.<\/p>\n\n\n\n<p>Sin\nembargo, perdi\u00f3 la batalla con otros navegadores como Mozilla Firefox o Google\nChrome. Los detractores del Explorer le achacaron lentitud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El fin de una era en la navegaci\u00f3n de internet llegar el 17 de agosto del pr\u00f3ximo a\u00f1o; Microsoft reconoce que es un \u2018paso dif\u00edcil\u2019. Microsoft anunci\u00f3 que dejar\u00e1 de darle mantenimiento a Internet Explorer, es decir, que dejar\u00e1 de funcionar a partir del 17 de agosto de 2021. En su blog, la compa\u00f1\u00eda tecnol\u00f3gica [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1996,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3,12],"tags":[],"class_list":{"0":"post-1995","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-internacional","8":"category-tecnologia-y-ciencia"},"jetpack_featured_media_url":"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2020\/08\/portada-1-logo-microsoft-edge.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/1995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/comments?post=1995"}],"version-history":[{"count":1,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/1995\/revisions"}],"predecessor-version":[{"id":1997,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/1995\/revisions\/1997"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media\/1996"}],"wp:attachment":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media?parent=1995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/categories?post=1995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/tags?post=1995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}