{"id":19755,"date":"2024-03-28T07:44:16","date_gmt":"2024-03-28T13:44:16","guid":{"rendered":"https:\/\/www.newsmillenium.com\/?p=19755"},"modified":"2024-03-28T07:44:32","modified_gmt":"2024-03-28T13:44:32","slug":"alcaldia-de-san-salvador-instalo-sistema-de-nebulizacion-en-la-plaza-gerardo-barrios-del-centro-historico","status":"publish","type":"post","link":"https:\/\/www.newsmillenium.com\/index.php\/2024\/03\/28\/alcaldia-de-san-salvador-instalo-sistema-de-nebulizacion-en-la-plaza-gerardo-barrios-del-centro-historico\/","title":{"rendered":"Alcald\u00eda de San Salvador instal\u00f3 sistema de nebulizaci\u00f3n en la plaza Gerardo Barrios del Centro Hist\u00f3rico"},"content":{"rendered":"\n<p>El alcalde de San Salvador, Mario Dur\u00e1n, gestion\u00f3 la instalaci\u00f3n de un sistema de nebulizaci\u00f3n para refrescar exteriores, en la plaza Gerardo Barrios del Centro Hist\u00f3rico, ante las altas temperaturas que permanecen en el territorio nacional.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>El sistema instalado, en el sector Nororiente de la plaza, est\u00e1 integrado por 28 nebulizadores que expulsan agua a un nivel aproximado de 10 metros de alto.<\/p>\n\n\n\n<p>Los cientos de familias capitalinas que visitan este espacio a diario se benefician con la implementaci\u00f3n de este novedoso sistema, que contribuye a minimizar el calor a trav\u00e9s de la pulverizaci\u00f3n de gotas de agua a alta presi\u00f3n, las cuales se evaporan con rapidez.<\/p>\n\n\n\n<p>El cuerpo de agua que se forma a trav\u00e9s de este sistema refresca a quienes transitan por la plaza Gerardo Barrios, mitigando significativamente el ambiente caluroso en este periodo vacacional de Semana Santa.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Durante esta semana, la alcald\u00eda de San Salvador ha organizado una amplia agenda de actividades culturales, art\u00edsticas y recreativas en las principales plazas del Coraz\u00f3n de El Salvador, para que nacionales y extranjeros disfruten de la Semana Mayor en la capital, en un ambiente de seguridad, orden y limpieza.<\/p>\n\n\n\n<p>La Direcci\u00f3n de Desechos S\u00f3lidos ejecuta un plan de limpieza especial en torno a las diferentes actividades religiosas y recreativas que se realizan en el Centro Hist\u00f3rico y los seis distritos de la capital.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Por su parte, el Cuerpo de Agentes Metropolitanos (CAM), de manera coordinada con la Polic\u00eda Nacional Civil (PNC), vela por la seguridad y convivencia ciudadana durante las actividades de Semana Santa y para ello implementa un plan de Seguridad del 24 al 31 de marzo.<\/p>\n\n\n\n<p>Asimismo, Protecci\u00f3n Civil Municipal y el departamento de Promoci\u00f3n de Salud acompa\u00f1an cada una de las procesiones y tienen presencia en las actividades culturales y recreativas, programadas en el Centro Hist\u00f3rico, 6 distritos y en los Centros de Convivencia Pedro Pablo Castillo y Sat\u00e9lite, donde est\u00e1n habilitadas piscinas gratuitas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"368\" src=\"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2024\/03\/portada-nebulizasor-2-1.jpg\" alt=\"\" class=\"wp-image-19757\" srcset=\"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2024\/03\/portada-nebulizasor-2-1.jpg 550w, https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2024\/03\/portada-nebulizasor-2-1-300x201.jpg 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El alcalde de San Salvador, Mario Dur\u00e1n, gestion\u00f3 la instalaci\u00f3n de un sistema de nebulizaci\u00f3n para refrescar exteriores, en la plaza Gerardo Barrios del Centro Hist\u00f3rico, ante las altas temperaturas que permanecen en el territorio nacional. El sistema instalado, en el sector Nororiente de la plaza, est\u00e1 integrado por 28 nebulizadores que expulsan agua a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":19756,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-19755","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-elsalvador"},"jetpack_featured_media_url":"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2024\/03\/portada-nebulizasor-1.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/19755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/comments?post=19755"}],"version-history":[{"count":1,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/19755\/revisions"}],"predecessor-version":[{"id":19758,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/19755\/revisions\/19758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media\/19756"}],"wp:attachment":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media?parent=19755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/categories?post=19755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/tags?post=19755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}