{"id":19666,"date":"2024-03-17T07:09:38","date_gmt":"2024-03-17T13:09:38","guid":{"rendered":"https:\/\/www.newsmillenium.com\/?p=19666"},"modified":"2024-03-17T07:09:44","modified_gmt":"2024-03-17T13:09:44","slug":"indes-gradua-a-la-tercera-generacion-de-arbitros-de-futbol","status":"publish","type":"post","link":"https:\/\/www.newsmillenium.com\/index.php\/2024\/03\/17\/indes-gradua-a-la-tercera-generacion-de-arbitros-de-futbol\/","title":{"rendered":"INDES grad\u00faa a la tercera generaci\u00f3n de \u00e1rbitros de f\u00fatbol"},"content":{"rendered":"\n<p>Elegantes y glamurosos los 88 r\u00e9feris de la zona oriental, paracentral, central y occidental del pa\u00eds, asistieron a la clausura del III Curso de Arbitraje que se llev\u00f3 a cabo a trav\u00e9s de la Gerencia de Desarrollo Deportivo del Instituto Nacional de los Deportes de El Salvador (INDES).<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La formaci\u00f3n fue impartida por Vladimir F\u00e9rnandez, coordinador nacional de arbitraje de la Copa Alevines y de los Juegos Nacionales Estudiantiles, quien desarroll\u00f3 la tem\u00e1tica del f\u00fatbol 11; mientras que las modalidades de playa y sala las imparti\u00f3 David Cruz.<\/p>\n\n\n\n<p>\u201cMe siento muy satisfecho, pues en este tercer curso de arbitraje contamos con la presencia de 18 se\u00f1oritas y 71 caballeros que se grad\u00faan hoy. Tenemos a los refer\u00eds Fernando Rivas y Wendy G\u00f3mez que ya dirigen juegos de f\u00fatbol playa en la fase municipal bajo la supervisi\u00f3n del instructor de la modalidad\u201d, expres\u00f3 F\u00e9rnandez.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Entre los colegiados que recibieron su acreditaci\u00f3n en las instalaciones del Estadio Nacional Jorge \u201cM\u00e1gico\u201d Gonz\u00e1lez se encontr\u00f3 en primera fila a Auda Pineda, de la zona oriental, quien ha formado parte del staff de \u00e1rbitros que pitaron en la Liga de F\u00fatbol Playa Copa CEL 2023.<\/p>\n\n\n\n<p>\u201cGracias a Dios ya es el tercer curso de arbitraje que recibo. Seguir prepar\u00e1ndonos es un privilegio que el INDES nos da porque uno nunca deja de aprender, pues la informaci\u00f3n siempre est\u00e1 cambiando y vienen nuevas reglas las cuales debemos estudiar para aplicarlas en el momento justo\u201d, coment\u00f3 Pineda.<\/p>\n\n\n\n<p>La formaci\u00f3n de referis continuar\u00e1 este a\u00f1o, pues gracias al inter\u00e9s que existe en todo el territorio nacional, el Departamento de Oportunidades pretende cerrar 2024 con el IV Curso de Arbitraje.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"332\" src=\"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2024\/03\/portada-1-2-arbitros-de-futbol.jpg\" alt=\"\" class=\"wp-image-19668\" srcset=\"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2024\/03\/portada-1-2-arbitros-de-futbol.jpg 550w, https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2024\/03\/portada-1-2-arbitros-de-futbol-300x181.jpg 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Elegantes y glamurosos los 88 r\u00e9feris de la zona oriental, paracentral, central y occidental del pa\u00eds, asistieron a la clausura del III Curso de Arbitraje que se llev\u00f3 a cabo a trav\u00e9s de la Gerencia de Desarrollo Deportivo del Instituto Nacional de los Deportes de El Salvador (INDES). La formaci\u00f3n fue impartida por Vladimir F\u00e9rnandez, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":19667,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-19666","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-elsalvador"},"jetpack_featured_media_url":"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2024\/03\/portada-1-arbitros-de-futbol.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/19666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/comments?post=19666"}],"version-history":[{"count":1,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/19666\/revisions"}],"predecessor-version":[{"id":19669,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/19666\/revisions\/19669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media\/19667"}],"wp:attachment":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media?parent=19666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/categories?post=19666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/tags?post=19666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}