{"id":18610,"date":"2023-12-07T11:39:28","date_gmt":"2023-12-07T17:39:28","guid":{"rendered":"https:\/\/www.newsmillenium.com\/?p=18610"},"modified":"2023-12-07T11:39:52","modified_gmt":"2023-12-07T17:39:52","slug":"tse-realizo-sorteo-de-posicion-de-banderas-y-elementos-en-las-papeletas-de-votacion","status":"publish","type":"post","link":"https:\/\/www.newsmillenium.com\/index.php\/2023\/12\/07\/tse-realizo-sorteo-de-posicion-de-banderas-y-elementos-en-las-papeletas-de-votacion\/","title":{"rendered":"TSE realizo Sorteo de posici\u00f3n de banderas y elementos  en las papeletas de votaci\u00f3n."},"content":{"rendered":"\n<p>Con presencia de los partidos pol\u00edticos, el Tribunal Supremo Electoral (TSE) realiz\u00f3 el acto de sorteo de posici\u00f3n de banderas y elementos distintivos de institutos pol\u00edticos o coaliciones en las papeletas de votaci\u00f3n.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Esta actividad se enmarc\u00f3 dentro de los preparativos del material electoral, que ser\u00e1 utilizado en las elecciones de presidente y vicepresidente de la Rep\u00fablica y Asamblea Legislativa del 4 de febrero y de concejos municipales y Parlamento Centroamericano, el 3 de marzo de 2024.<\/p>\n\n\n\n<p>El TSE cumpli\u00f3 con el principio de equidad en el trato a los partidos pol\u00edticos para que todos tuviesen las mismas oportunidades en la distribuci\u00f3n de posiciones. Este procedimiento fue un paso previo al inicio de la impresi\u00f3n de un aproximado de 24 millones de papeletas, que ser\u00e1n dispuestas en los 1,595 centros de votaci\u00f3n del territorio nacional.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"290\" src=\"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2023\/12\/portada-1-pappeleta-diputados.jpg\" alt=\"\" class=\"wp-image-18612\" srcset=\"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2023\/12\/portada-1-pappeleta-diputados.jpg 550w, https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2023\/12\/portada-1-pappeleta-diputados-300x158.jpg 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/figure>\n\n\n\n<p>Para definir la ubicaci\u00f3n de los elementos distintivos, como banderas, fotograf\u00edas y nombres de los candidatos, el TSE dispuso de un procedimiento transparente en donde los representantes de partidos participaron activamente en el sorteo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Este importante evento cont\u00f3 con la presencia de la Junta de Vigilancia Electoral, representantes de partidos, medios de comunicaci\u00f3n y la fiscal\u00eda electoral, que son testigos que dan fe de la transparencia, con la que se desarrollan estas actividades del calendario electoral.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con presencia de los partidos pol\u00edticos, el Tribunal Supremo Electoral (TSE) realiz\u00f3 el acto de sorteo de posici\u00f3n de banderas y elementos distintivos de institutos pol\u00edticos o coaliciones en las papeletas de votaci\u00f3n. Esta actividad se enmarc\u00f3 dentro de los preparativos del material electoral, que ser\u00e1 utilizado en las elecciones de presidente y vicepresidente de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18611,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-18610","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-elsalvador"},"jetpack_featured_media_url":"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2023\/12\/portada-1-pappeleta-presidente.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/18610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/comments?post=18610"}],"version-history":[{"count":1,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/18610\/revisions"}],"predecessor-version":[{"id":18613,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/18610\/revisions\/18613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media\/18611"}],"wp:attachment":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media?parent=18610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/categories?post=18610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/tags?post=18610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}