{"id":17776,"date":"2023-10-02T09:38:38","date_gmt":"2023-10-02T15:38:38","guid":{"rendered":"https:\/\/www.newsmillenium.com\/?p=17776"},"modified":"2023-10-02T09:38:40","modified_gmt":"2023-10-02T15:38:40","slug":"selection-camp-de-la-jr-nba-finaliza-con-el-juego-de-las-estrellas-y-mensajes-motivadores","status":"publish","type":"post","link":"https:\/\/www.newsmillenium.com\/index.php\/2023\/10\/02\/selection-camp-de-la-jr-nba-finaliza-con-el-juego-de-las-estrellas-y-mensajes-motivadores\/","title":{"rendered":"Selection Camp de la Jr. NBA finaliza con el Juego de las Estrellas y mensajes motivadores"},"content":{"rendered":"\n<p>Con un mensaje motivador del presidente ad hon\u00f3rem del Instituto Nacional de los Deportes de El Salvador (INDES), Yamil Bukele, la entrega de diplomas y camisas se baj\u00f3 el tel\u00f3n del Selection Camp de la Jr. NBA League, que cont\u00f3 con la participaci\u00f3n del exjugador de la NBA, Carl Herrera, dos veces campe\u00f3n con los Rockets de Houston.<\/p>\n\n\n\n<p>En el programa del tercer y \u00faltimo d\u00eda destac\u00f3 la selecci\u00f3n de los 12 chicos y chicas para el Juego de las Estrellas.<\/p>\n\n\n\n<p>El campamento fue un convivio deportivo de alto nivel y mucho aprendizaje para los 100 mejores jugadores (50 ni\u00f1os y 50 ni\u00f1as) menores de 14 a\u00f1os que participaron en el torneo de baloncesto dentro de los Juegos Deportivos Estudiantiles Nacionales, que reactiv\u00f3 el INDES.<\/p>\n\n\n\n<p>Yamil Bukele felicit\u00f3 a los atletas y los inst\u00f3 a poner en pr\u00e1ctica los conocimientos adquiridos durante los tres d\u00edas de actividad del Selection Camp que dirigi\u00f3 la espa\u00f1ola Lorena Infantes, jefa de Operaciones de NBA Latinoam\u00e9rica.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u201cQuiero desearles suerte y apliquen los conocimientos que les han ense\u00f1ado durante estos d\u00edas, yo tambi\u00e9n soy part\u00edcipe de que todos los sue\u00f1os se pueden hacer realidad, nada en la vida es f\u00e1cil, pero depende de nuestra actitud, de nuestra disciplina y de nuestra perseverancia para que esos sue\u00f1os, que cada uno de ustedes se ha trazado, sean m\u00e1s f\u00e1cil de lograr\u201d, coment\u00f3 el titular del instituto.<\/p>\n\n\n\n<p>\u201cDe todo coraz\u00f3n, estoy muy contento por ustedes, que Dios los bendiga y feliz regreso a casa. Nos vemos el pr\u00f3ximo a\u00f1o en los Juegos Estudiantiles que estar\u00e1n acompa\u00f1ados por Jr. NBA League\u201d, enfatiz\u00f3 el presidente ad hon\u00f3rem del INDES.<\/p>\n\n\n\n<p>Bukele tambi\u00e9n agradeci\u00f3 a la organizaci\u00f3n de la NBA y al Programa de la Jr. NBA League por la confianza y a todo el equipo que apoy\u00f3 en hizo posible el desarrollo de este campamento.<\/p>\n\n\n\n<p>Por su parte, el ex alero venezolano recalc\u00f3 a los ni\u00f1os a mantener la disciplina, respeto y compa\u00f1erismo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>\u201cAprendieron disciplina, respeto y trabajo de conjunto que los va a llevar adonde ustedes quieren llegar y espero que este campamento se repita en otros escenarios. Muchas gracias y se les quiere mucho\u201d, dijo Herrera en la duela del Complejo Deportivo de la Universidad de El Salvador.<\/p>\n\n\n\n<p>\u201cPara m\u00ed amigo Yamil Bukele con todo el cari\u00f1o del mundo\u201d, fue el mensaje que escribi\u00f3 Carl Herrera, dos veces campe\u00f3n con los Houston Rockets, en una postal suya que autografi\u00f3 al presidente ad hon\u00f3rem del INDES.<\/p>\n\n\n\n<p>\u201cGracias por la entrega, por la energ\u00eda, por las sonrisas de cada d\u00eda y el esfuerzo. Como dijo Carl y Yamil nunca dejen de so\u00f1ar, los sue\u00f1os se cumplen con trabajo, disciplina y esfuerzo\u201d, recalc\u00f3 Lorena Infantes.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Juego de las Estrellas<\/p>\n\n\n\n<p>El equipo del Este gan\u00f3 16-14 al del Oeste en el Juego de las Estrellas femenino del Selection Camp.<\/p>\n\n\n\n<p>El cuadro del Este lo conformaron Liliana Flores, Nahomy Salinas, Ashley Orantes, Mar\u00eda Jos\u00e9 Calder\u00f3n, Renata Sandoval y Fabiola Bruno<\/p>\n\n\n\n<p>En el representativo del Oeste jugaron Karen Garc\u00eda, Naomi S\u00e1nchez, Marta Valdes, Jennifer Mart\u00ednez, Aracely Hern\u00e1ndez y F\u00e1tima Salamanca.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"311\" src=\"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2023\/10\/portada-1-2-yamil-NBA-jr.jpg\" alt=\"\" class=\"wp-image-17778\" srcset=\"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2023\/10\/portada-1-2-yamil-NBA-jr.jpg 550w, https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2023\/10\/portada-1-2-yamil-NBA-jr-300x170.jpg 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/figure>\n\n\n\n<p>En masculino, el ganador del All Star fue el equipo del Este, conformado por Daniel Quintanilla, Kevin Palacios, Jos\u00e9 Rivas Vadillo, Mauricio Granados, Arturo Gonz\u00e1lez y Gabriel G\u00e1mez, que vencieron 31-24 al del Oeste, que estuvo integrado por Lev\u00ed Portillo, Jorge Barrientos, Anthony Stevens, Fernando Noel, Santiago Portillo y Erick Guidos.<\/p>\n\n\n\n<p>Ashley Nicole Orantes y Jos\u00e9 Brian Rivas Vadillo fueron elegidos como MVP del Juego de las Estrellas femenino y masculino, respectivamente..<\/p>\n\n\n\n<p>Al final de la actividad, Bukele y Herrera entregaron una camisa del campamento y un diploma a los 100 jugadores participantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con un mensaje motivador del presidente ad hon\u00f3rem del Instituto Nacional de los Deportes de El Salvador (INDES), Yamil Bukele, la entrega de diplomas y camisas se baj\u00f3 el tel\u00f3n del Selection Camp de la Jr. NBA League, que cont\u00f3 con la participaci\u00f3n del exjugador de la NBA, Carl Herrera, dos veces campe\u00f3n con los [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17777,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[5],"tags":[],"class_list":{"0":"post-17776","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deportes"},"jetpack_featured_media_url":"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2023\/10\/portada-1-yamil-NBA-jr.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/17776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/comments?post=17776"}],"version-history":[{"count":1,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/17776\/revisions"}],"predecessor-version":[{"id":17779,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/17776\/revisions\/17779"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media\/17777"}],"wp:attachment":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media?parent=17776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/categories?post=17776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/tags?post=17776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}