{"id":17370,"date":"2023-08-26T10:42:14","date_gmt":"2023-08-26T16:42:14","guid":{"rendered":"https:\/\/www.newsmillenium.com\/?p=17370"},"modified":"2023-08-26T10:42:17","modified_gmt":"2023-08-26T16:42:17","slug":"barra-de-santiago-campeon-de-copa-de-la-lfp","status":"publish","type":"post","link":"https:\/\/www.newsmillenium.com\/index.php\/2023\/08\/26\/barra-de-santiago-campeon-de-copa-de-la-lfp\/","title":{"rendered":"Barra de Santiago, campe\u00f3n de Copa de la LFP"},"content":{"rendered":"\n<p>El equipo masculino de Barra de Santiago derrot\u00f3 7-6 a San Sebasti\u00e1n en la final de Copa de la Liga de F\u00fatbol playa (LFP) Copa CEL 2023, consagr\u00e1ndose campe\u00f3n por primera vez en la disputa por este trofeo.<\/p>\n\n\n\n<p>Los ahuachapanecos sumaron su tercer t\u00edtulo en su paso por la LFP (dos ligas y una copa) y ahora se preparan para enfrentar de manera positiva la fase de cuartos de final de la liga, que inicia este pr\u00f3ximo s\u00e1bado.<\/p>\n\n\n\n<p>El duelo fue parejo hasta el \u00faltimo minuto del tercer per\u00edodo, por lo que el camino al triunfo no fue f\u00e1cil, ya que los barre\u00f1os comenzaron perdiendo tras un gol del goleador del grupo B, \u00d3scar Flores, quien con un disparo de media distancia, coloc\u00f3 el 1-0 a favor de San Sebasti\u00e1n.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Pero el empate no tard\u00f3 en llegar. La paridad en el marcador lo coloc\u00f3 Anderson Castro tras una jugada en conjunto con Frank Vel\u00e1squez que le permiti\u00f3 anotar el 1-1. Un minuto despu\u00e9s, en una mala marca de la defensa de la isla, Castro firm\u00f3 el segundo en su cuenta personal y puso el 2-1 parcial.<\/p>\n\n\n\n<p>Eso s\u00ed, la reacci\u00f3n de los usulutecos lleg\u00f3 por medio del capit\u00e1n Elmer Robles que no dud\u00f3 en pegarle al bal\u00f3n con potencia y emparejar las acciones (2-2), marcador con el que termin\u00f3 el primer per\u00edodo.<\/p>\n\n\n\n<p>En el segundo episodio, el conjunto de la Barra rompi\u00f3 el empate con apenas un minuto de juego, cuando el cierre Herber Ramos marc\u00f3 para poner el 3-2.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Un nuevo empate en el marcador (3-3) llegar\u00eda con un golazo del capit\u00e1n de San Sebasti\u00e1n, Elmer Robles, tras ejecutar a la perfecci\u00f3n una chilena que dej\u00f3 sin oportunidad al arquero de la Barra.<\/p>\n\n\n\n<p>Los de la Barra de Santiago tomaron ventaja en el marcador por 4-3 despu\u00e9s de un penal bien cobrado del norteamericano Tanner Akol, que le dio un peque\u00f1o momento de tranquilidad a los occidentales.<\/p>\n\n\n\n<p>Para goce de los presentes, los goles no dejaban de llegar. El gol puso el 4-4 en la pizarra fue anotado por Rudy Vasquez, de San Sebasti\u00e1n.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Para el inicio del \u00faltimo per\u00edodo, sobre los primeros tres minutos de juego, ambas escuadras lucharon sin \u00e9xito por eliminar el empate. Hasta que un potente disparo de Heber Ramos hizo vibrar a los aficionados en las gradas del estadio y puso el 5-4 a favor de los de la Barra.<\/p>\n\n\n\n<p>Sin embargo, Robles volvi\u00f3 a perforar las redes de la Barra de Santiago, esta vez para poner el 5-5 desde punto penal.<\/p>\n\n\n\n<p>Pero el goleador hist\u00f3rico de la selecci\u00f3n, Frank Vel\u00e1squez, respondi\u00f3 con una chilena que rompi\u00f3 la paridad y le dio la ventaja moment\u00e1nea a la Barra. La celebraci\u00f3n del dorsal 27 de la Barra se alarg\u00f3, pues se encarg\u00f3 de firmar otro tanto y poner el 7-5 parcial.<\/p>\n\n\n\n<p>Al final del partido, Jorge Flores, de San Sebasti\u00e1n, envi\u00f3 un centro a media altura que \u00d3scar Flores cabece\u00f3 con certeza para descontar el definitivo 7-6 que le dio la copa al equipo de la Barra de Santiago.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El equipo masculino de Barra de Santiago derrot\u00f3 7-6 a San Sebasti\u00e1n en la final de Copa de la Liga de F\u00fatbol playa (LFP) Copa CEL 2023, consagr\u00e1ndose campe\u00f3n por primera vez en la disputa por este trofeo. Los ahuachapanecos sumaron su tercer t\u00edtulo en su paso por la LFP (dos ligas y una copa) [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17371,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[5],"tags":[],"class_list":{"0":"post-17370","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deportes"},"jetpack_featured_media_url":"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2023\/08\/portad-1-M-San-Sebastian-vs-Barra-de-Santiago-Final-Copa-LFP-.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/17370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/comments?post=17370"}],"version-history":[{"count":1,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/17370\/revisions"}],"predecessor-version":[{"id":17372,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/17370\/revisions\/17372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media\/17371"}],"wp:attachment":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media?parent=17370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/categories?post=17370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/tags?post=17370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}