{"id":16946,"date":"2023-07-15T08:45:50","date_gmt":"2023-07-15T14:45:50","guid":{"rendered":"https:\/\/www.newsmillenium.com\/?p=16946"},"modified":"2023-07-15T08:45:53","modified_gmt":"2023-07-15T14:45:53","slug":"natacion-y-ajedrez-aportaron-medallas-para-la-ues","status":"publish","type":"post","link":"https:\/\/www.newsmillenium.com\/index.php\/2023\/07\/15\/natacion-y-ajedrez-aportaron-medallas-para-la-ues\/","title":{"rendered":"Nataci\u00f3n y ajedrez aportaron medallas para la UES"},"content":{"rendered":"\n<p>Las nacionales Grecia Mendoza, Karla Pe\u00f1a, Berenice Chavarr\u00eda y Paola Orellana ganaron medalla de oro en los 400 metros relevo combinado de la nataci\u00f3n y la ajedrecista Alejandra Zavala sum\u00f3 dos preseas m\u00e1s al medallero salvadore\u00f1o de los VIII Juegos Deportivos Universitarios Centroamericanos (JUDUCA) 2023.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>En m\u00e1s resultados de nataci\u00f3n, Otto Borgards se agenci\u00f3 dos medallas de oro en 50 y 100 metros pecho, durante el \u00faltimo d\u00eda de competencias para la nataci\u00f3n.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>En otras pruebas, Mendoza se adjudic\u00f3 hoy la medalla de plata en los 200 metros combinado, mientras que Paola Orellana se agenci\u00f3 plata en los 50 metros libres y bronce en los 100 mariposa. Tambi\u00e9n, Fernando S\u00e1nchez gan\u00f3 medalla de bronce en los 100 metros dorso.<\/p>\n\n\n\n<p>Es por eso que para Grecia, estudiante de segundo a\u00f1o de veterinaria de la UES y reci\u00e9n ganadora de medalla de bronce por equipo en nataci\u00f3n art\u00edstica de los Juegos Centroamericanos y del Caribe San Salvador 2023, haber conseguido dos medallas en una competencia de tanta importancia y en modalidades que no son su fuerte es algo que tiene mucho valor.<\/p>\n\n\n\n<p>&#8220;Para m\u00ed fue muy gratificante lograr medalla en relevo junto a mis compa\u00f1eras y sumar al medallero para la Universidad. Todos nos esforzamos al m\u00e1ximo y estamos muy satisfechos con las pruebas nadadas. Haber competido en pruebas que no son mi fuerte fue un reto m\u00e1s en mi carrera deportiva&#8221;, expres\u00f3 Mendoza.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>La atleta, integrante del Programa Esfuerzo y Gloria, afirm\u00f3 que para ser la primera vez que participa en unos juegos universitarios a nivel de la regional fue un excelente resultado.<\/p>\n\n\n\n<p>&#8220;Estos son mis primeros JUDUCA, desconoc\u00eda el nivel de los dem\u00e1s competidores y, la verdad, son muy fuertes. Sab\u00edamos que iba a ser dif\u00edcil, pero no imposible lograr medalla&#8221;, indic\u00f3.<\/p>\n\n\n\n<p>Mientras que en ajedrez, Alejandra Zavala, Camilo Medrano y Sa\u00fal Martell sumaron cuatro medallas para los intereses de la Universidad de El Salvador.<\/p>\n\n\n\n<p>Zavala obtuvo dos preseas doradas al ganar la modalidad cl\u00e1sica individual femenina y la modalidad blitz individual femenina.<\/p>\n\n\n\n<p>La nacional expres\u00f3 su alegr\u00eda por representar a su alma mater en su \u00faltimo a\u00f1o de estudios, pues est\u00e1 a punto de graduarse como licenciada en geof\u00edsica.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>&#8220;Fue una competencia bastante fuerte. En mi caso, estuve en el individual femenino donde gan\u00e9 medalla de oro en la categor\u00eda convencional y tambi\u00e9n un oro en la modalidad de Blitz. En m\u00e1s resultados para la UES, en el tablero uno, logramos bronce con Camilo Medrano y, en el tablero cinco, tambi\u00e9n ganamos bronce con Sa\u00fal Martel&#8221;, explic\u00f3 Zavala.<\/p>\n\n\n\n<p>Por otra parte, Alejandra manifest\u00f3 sentirse contenta y satisfecha tras subir al podio representando a su universidad.<\/p>\n\n\n\n<p>&#8220;Estos son mis \u00faltimos juegos universitarios, as\u00ed que es bonito despedirse de esta forma de la universidad. Estudio licenciatura en geof\u00edsica y estoy pr\u00e1cticamente en el \u00faltimo a\u00f1o, es una buena forma de decirle adi\u00f3s a esta que ha sido mi casa durante muchos a\u00f1os&#8221;, asegur\u00f3 Zavala.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>En semifinales de f\u00fatbol sala femenino, la Universidad Nacional de Costa Rica (UNA) gan\u00f3 3-0 a la Universidad Aut\u00f3noma de Honduras (UNAH). Mientras que, la Universidad Tecnol\u00f3gica de Costa Rica (UTN) empat\u00f3 3-3 ante el Tecnol\u00f3gico de Costa Rica (TEC), ganando en penales 2-1 la TEC.<\/p>\n\n\n\n<p>En tanto en masculino, la UNAH venci\u00f3 5-4 a la Universidad Pedag\u00f3gica Nacional Francisco Moraz\u00e1n, de Honduras (UPNFM); en tanto, la UNA perdi\u00f3 1-2 ante la TEC.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las nacionales Grecia Mendoza, Karla Pe\u00f1a, Berenice Chavarr\u00eda y Paola Orellana ganaron medalla de oro en los 400 metros relevo combinado de la nataci\u00f3n y la ajedrecista Alejandra Zavala sum\u00f3 dos preseas m\u00e1s al medallero salvadore\u00f1o de los VIII Juegos Deportivos Universitarios Centroamericanos (JUDUCA) 2023. En m\u00e1s resultados de nataci\u00f3n, Otto Borgards se agenci\u00f3 dos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":16947,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[5],"tags":[],"class_list":{"0":"post-16946","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deportes"},"jetpack_featured_media_url":"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2023\/07\/portada-1-juegos-universit.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/16946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/comments?post=16946"}],"version-history":[{"count":1,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/16946\/revisions"}],"predecessor-version":[{"id":16948,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/16946\/revisions\/16948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media\/16947"}],"wp:attachment":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media?parent=16946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/categories?post=16946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/tags?post=16946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}