{"id":15179,"date":"2023-03-17T06:45:47","date_gmt":"2023-03-17T12:45:47","guid":{"rendered":"https:\/\/www.newsmillenium.com\/?p=15179"},"modified":"2023-03-17T06:50:19","modified_gmt":"2023-03-17T12:50:19","slug":"se-viene-el-torneo-apertura-2023-copa-tigo-sports-de-la-liga-nacional-de-futbo","status":"publish","type":"post","link":"https:\/\/www.newsmillenium.com\/index.php\/2023\/03\/17\/se-viene-el-torneo-apertura-2023-copa-tigo-sports-de-la-liga-nacional-de-futbo\/","title":{"rendered":"Se viene el Torneo Apertura 2023 Copa Tigo Sports de la Liga Nacional de F\u00fatbol\u00a0\u00a0\ufffc"},"content":{"rendered":"\n<p>Todo est\u00e1 listo para que el pr\u00f3ximo s\u00e1bado vuelva a rodar el bal\u00f3n en la disputa del Torneo Apertura 2023 Copa Tigo Sports de la Liga Nacional de F\u00fatbol (LNF), que nuevamente contar\u00e1 con la participaci\u00f3n de 14 equipos y en donde Santa Ana Municipal buscar\u00e1 revalidar su t\u00edtulo.<\/p>\n\n\n\n<p>El lanzamiento de la segunda edici\u00f3n del torneo fue realizado por el presidente ad hon\u00f3rem del Instituto Nacional de los Deportes de El Salvador (INDES), Yamil Bukele, quien estuvo acompa\u00f1ado por alcaldes y representantes de las 14 cabeceras departamentales del pa\u00eds.<\/p>\n\n\n\n<p>\u201cFC Ahuachap\u00e1n, Alacranes FC, AD Cuscatleco, La Paz FC, CD Sonsonate, CD Atl\u00e9tico La Uni\u00f3n, San Vicente FC, Caba\u00f1as FC, Moraz\u00e1n FC, CD Usulut\u00e1n, San Miguel FC, San Salvador FC y Santa Tecla ITD FC son los otros 13 equipos que pelear\u00e1n por el t\u00edtulo\u201d, detall\u00f3 el presidente ad hon\u00f3rem del INDES.<\/p>\n\n\n\n<p>\u201cSigo convencido de que la Liga Nacional de F\u00fatbol es necesaria para abrir puertas para la juventud de El Salvador, para que muestren su verdadero potencial deportivo, pero, sobre todo, para generar oportunidades para el desarrollo local a trav\u00e9s del deporte\u201d, enfatiz\u00f3 Bukele.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"625\" height=\"419\" src=\"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2023\/03\/portada-3-Conferencia-Lanzamiento-Liga-Nacional-de-Futbol-2023-16032023_12.jpg\" alt=\"\" class=\"wp-image-15181\" srcset=\"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2023\/03\/portada-3-Conferencia-Lanzamiento-Liga-Nacional-de-Futbol-2023-16032023_12.jpg 625w, https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2023\/03\/portada-3-Conferencia-Lanzamiento-Liga-Nacional-de-Futbol-2023-16032023_12-300x201.jpg 300w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><\/figure>\n\n\n\n<p>El funcionario recalc\u00f3 que la LNF tiene que verse como una oportunidad para los j\u00f3venes y no como una competencia para las ligas profesionales. \u201cEsto es una ventana para que la juventud muestre su talento. Nuestro objetivo sigue siendo que la Liga Nacional de F\u00fatbol se convierta en el semillero para los equipos y selecciones nacionales\u201d, recalc\u00f3 Bukele.<\/p>\n\n\n\n<p>El presidente del INDES record\u00f3 que ocho jugadores que militaron en la edici\u00f3n inicial de la LNF firmaron posteriormente con equipos profesionales del f\u00fatbol salvadore\u00f1o. Adem\u00e1s, cuatro elementos m\u00e1s se encuentran en Portugal, en un centro de alto rendimiento, gracias a las visorias realizadas en conjunto con BSports.&nbsp;<\/p>\n\n\n\n<p>Seg\u00fan detall\u00f3 el titular del INDES, los equipos participantes en el Apertura 2023 de la LNF estar\u00e1n integrados por 25 jugadores, 20 de ellos con edad m\u00e1xima de 21 a\u00f1os y m\u00ednima de 15, nacidos en el departamento del equipo donde juegan; tres mayores de 21 a\u00f1os que pueden haber nacido en cualquier otro departamento y dos extranjeros sin l\u00edmite de edad.&nbsp;<\/p>\n\n\n\n<p>Asimismo, el funcionario explic\u00f3 que cada equipo recibir\u00e1 $20 mil, uniformes para jugadores y cuerpo t\u00e9cnico, un set de balones Joma, cuota de hidrataci\u00f3n y el respectivo pago de arbitraje.<\/p>\n\n\n\n<p>La inauguraci\u00f3n oficial del torneo se efectuar\u00e1 en el estadio \u00d3scar Quite\u00f1o, donde los pumas recibir\u00e1n a los ocelotes de Usulut\u00e1n. La jornada de ese d\u00eda se completar\u00e1 con los juegos en el estadio Alonso Alegr\u00eda, donde Cuscatl\u00e1n tendr\u00e1 la visita de San Miguel.<\/p>\n\n\n\n<p>La primera jornada se completa con cinco juegos el domingo 19.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todo est\u00e1 listo para que el pr\u00f3ximo s\u00e1bado vuelva a rodar el bal\u00f3n en la disputa del Torneo Apertura 2023 Copa Tigo Sports de la Liga Nacional de F\u00fatbol (LNF), que nuevamente contar\u00e1 con la participaci\u00f3n de 14 equipos y en donde Santa Ana Municipal buscar\u00e1 revalidar su t\u00edtulo. El lanzamiento de la segunda edici\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":15180,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[2],"tags":[],"class_list":{"0":"post-15179","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-featured"},"jetpack_featured_media_url":"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2023\/03\/portada-1-Conferencia-Lanzamiento-Liga-Nacional-de-Futbol-2023-16032023_02.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/15179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/comments?post=15179"}],"version-history":[{"count":2,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/15179\/revisions"}],"predecessor-version":[{"id":15188,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/15179\/revisions\/15188"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media\/15180"}],"wp:attachment":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media?parent=15179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/categories?post=15179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/tags?post=15179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}