{"id":14061,"date":"2023-01-16T07:31:17","date_gmt":"2023-01-16T13:31:17","guid":{"rendered":"https:\/\/www.newsmillenium.com\/?p=14061"},"modified":"2023-01-16T07:46:58","modified_gmt":"2023-01-16T13:46:58","slug":"syngenta-presenta-la-plataforma-proagricultor-en-el-salvado","status":"publish","type":"post","link":"https:\/\/www.newsmillenium.com\/index.php\/2023\/01\/16\/syngenta-presenta-la-plataforma-proagricultor-en-el-salvado\/","title":{"rendered":"Syngenta presenta la plataforma #PROagricultor en El Salvador\ufffc"},"content":{"rendered":"\n<p>Comprometida con la generaci\u00f3n de un cambio positivo en la forma en que se producen los alimentos, Syngenta lanza #PROagricultor, una plataforma de educaci\u00f3n virtual gratuita y abierta a todo el p\u00fablico, enfocada en la capacitaci\u00f3n en agricultura regenerativa.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>#PROagricultor es una herramienta que busca capacitar a agricultores, agroindustria, estudiantes y t\u00e9cnicos agr\u00edcolas, mediante la ense\u00f1anza de mejores pr\u00e1cticas habilitadas por tecnolog\u00eda de punta para desarrollar sistemas alimentarios resilientes y pr\u00f3speros que garanticen el bienestar de los agricultores, que contribuyan a la restauraci\u00f3n del suelo, la conservaci\u00f3n de la biodiversidad, del agua y la desaceleraci\u00f3n del cambio clim\u00e1tico.<\/li><\/ul>\n\n\n\n<p>La plataforma cuenta con 5 m\u00f3dulos que abordan los temas de:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Buen uso y manejo responsable de productos para la protecci\u00f3n de cultivos<\/li><li>Biodiversidad en mi finca<\/li><li>Certificadores y est\u00e1ndares agr\u00edcolas<\/li><li>Salud del suelo<\/li><li>Y el quinto m\u00f3dulo en Manejo Integrado de Plagas que fue recientemente lanzado en el mes de septiembre de 2022<\/li><li>Despu\u00e9s de su m\u00e1s reciente lanzamiento, la plataforma continuar\u00e1 trabajando en el desarrollo de nuevos m\u00f3dulos en las diferentes tem\u00e1ticas que componen la agricultura regenerativa.<\/li><\/ul>\n\n\n\n<p>La compleci\u00f3n exitosa de cada uno de los m\u00f3dulos es certificada por la plataforma mediante la generaci\u00f3n de diplomas personalizados con los datos del usuario, especificando cu\u00e1les fueron las tem\u00e1ticas cursadas. Las certificaciones est\u00e1n avaladas por Syngenta y por los colaboradores que participaron en su construcci\u00f3n.<\/p>\n\n\n\n<p>Cada m\u00f3dulo de #PROagricultor aborda una tem\u00e1tica diferente y por lo tanto, su desarrollo cont\u00f3 con la colaboraci\u00f3n de diferentes centros de investigaci\u00f3n, ONGs, certificadoras y expertos sectoriales, como Oliver Bach de la Sustainable Agriculture Network (SAN); Marco Villegas de Global G.A.P.; Gisela Kopper del Laboratorio Tecnol\u00f3gico del Uruguay (LSQA); Miguel Hern\u00e1ndez de Bonsucro; Yasmina Neustadtl de la Roundtable on Sustainable Palm Oil (RSPO) y Jelle Van Loon del Centro Internacional de Mejoramiento de Ma\u00edz y Trigo (CIMMYT).<\/p>\n\n\n\n<p>Con el prop\u00f3sito de generar un aprendizaje din\u00e1mico, la plataforma cuenta con videos pr\u00e1cticos, audios interactivos, transmisiones en vivo con expertos, im\u00e1genes e infograf\u00edas, juegos y certificados.<\/p>\n\n\n\n<p>#PROagricultor se lanza ahora en El Salvador, tambi\u00e9n se encuentra disponible en los pa\u00edses centroamericanos como Guatemala y Costa Rica. Adem\u00e1s de 20 pa\u00edses de Latinoam\u00e9rica, desde M\u00e9xico hasta Per\u00fa, Argentina, Bolivia, Paraguay, Uruguay y Chile.<\/p>\n\n\n\n<p>La nueva plataforma busca promover acciones consecuentes con las problem\u00e1ticas globales actuales como el cambio clim\u00e1tico, la necesidad de garantizar el campo a futuras generaciones, la protecci\u00f3n de la biodiversidad y promoci\u00f3n del uso adecuado de recursos naturales.<\/p>\n\n\n\n<p>Pensando en su grupo objetivo, la plataforma fue dise\u00f1ada para ser accesible desde cualquier navegador y dispositivo inteligente, con la posibilidad de guardar el progreso alcanzado por el usuario, su compatibilidad con redes 3G permite el uso en \u00e1reas de menor cobertura en conectividad.<\/p>\n\n\n\n<p>#PROgricultor, la plataforma de capacitaci\u00f3n online gratuita para una agricultura sostenible se puede acceder en <a href=\"http:\/\/www.proagricultor.com\">www.proagricultor.com<\/a><\/p>\n\n\n\n<p>La plataforma busca construir una comunidad denominada <em>Los H\u00e9roes del Campo<\/em>, conformada por agricultores y actores de la industria agr\u00edcola que participan activamente dentro de la din\u00e1mica social y contribuyen con la alimentaci\u00f3n del mundo, a trav\u00e9s de la capacitaci\u00f3n para impulsar la transici\u00f3n hacia un modelo de agricultura regenerativa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comprometida con la generaci\u00f3n de un cambio positivo en la forma en que se producen los alimentos, Syngenta lanza #PROagricultor, una plataforma de educaci\u00f3n virtual gratuita y abierta a todo el p\u00fablico, enfocada en la capacitaci\u00f3n en agricultura regenerativa. #PROagricultor es una herramienta que busca capacitar a agricultores, agroindustria, estudiantes y t\u00e9cnicos agr\u00edcolas, mediante la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":14062,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[17],"tags":[],"class_list":{"0":"post-14061","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-excelencia-empresarial"},"jetpack_featured_media_url":"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2023\/01\/portada-1-agro-1.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/14061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/comments?post=14061"}],"version-history":[{"count":1,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/14061\/revisions"}],"predecessor-version":[{"id":14063,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/14061\/revisions\/14063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media\/14062"}],"wp:attachment":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media?parent=14061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/categories?post=14061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/tags?post=14061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}