{"id":13631,"date":"2022-12-09T08:50:39","date_gmt":"2022-12-09T14:50:39","guid":{"rendered":"https:\/\/www.newsmillenium.com\/?p=13631"},"modified":"2022-12-09T08:50:43","modified_gmt":"2022-12-09T14:50:43","slug":"en-soyapango-el-gobierno-emplea-equipo-con-tecnologia-de-punta-para-buscar-y-capturar-a-los-pandilleros","status":"publish","type":"post","link":"https:\/\/www.newsmillenium.com\/index.php\/2022\/12\/09\/en-soyapango-el-gobierno-emplea-equipo-con-tecnologia-de-punta-para-buscar-y-capturar-a-los-pandilleros\/","title":{"rendered":"En Soyapango, el Gobierno emplea equipo con tecnolog\u00eda de punta para buscar y capturar a los pandilleros"},"content":{"rendered":"\n<p>El Gobierno est\u00e1 ganando la Guerra contra las pandillas. En el cerco de seguridad montado en el municipio de Soyapango, las tropas est\u00e1n equipadas con modernos equipos tecnol\u00f3gicos para localizar y encontrar a los pandilleros que est\u00e1n acorralados en algunas colonias.<\/p>\n\n\n\n<p>Con el uso de drones, veh\u00edculos blindados de \u00faltima generaci\u00f3n equipados con modernos sistemas electr\u00f3nicos, las unidades de seguridad peinan cada cent\u00edmetro de Soyapango en b\u00fasqueda de terroristas escondidos.<\/p>\n\n\n\n<p>La movilizaci\u00f3n de tropas, como nunca se hab\u00eda visto en El Salvador, de 10,000 hombres, para derrotar a los enemigos de la poblaci\u00f3n, tomaron m\u00e1s de 40 posiciones estrat\u00e9gicas en el referido municipio desde el s\u00e1bado pasado en la madrugada.<\/p>\n\n\n\n<p>Los funcionarios del Gobierno del Presidente Nayib Bukele anunciaron la entrega de 1,300 cascos bal\u00edsticos, 2,000 placas bal\u00edsticas (escudos), 184 c\u00e1maras t\u00e1cticas y auriculares a personal que ejecuta la Fase Cinco del Plan Control Territorial.<\/p>\n\n\n\n<p>El Gobierno del Presidente Nayib Bukele ha invertido $1.1 millones solamente en la adquisici\u00f3n del nuevo equipo.<\/p>\n\n\n\n<p>La entrega del equipamiento t\u00e1ctico forma parte del programa de modernizaci\u00f3n de las instituciones de seguridad, que orden\u00f3 el Presidente Nayib Bukele.<\/p>\n\n\n\n<p>Como producto de las acciones del cerco de seguridad en Soyapango se contabiliza la captura de 275 pandilleros de los distintos grupos criminales.<\/p>\n\n\n\n<p>Con la entrada en vigor del r\u00e9gimen de excepci\u00f3n, en vigor desde el 27 de marzo pasado, van 59,307 pandilleros capturados a escala nacional, estas detenciones han dado como resultado que en el pa\u00eds haya tranquilidad ya que ahora el control territorial lo ejerce el Estado.<\/p>\n\n\n\n<p>En las pr\u00f3ximas semanas se har\u00e1 entrega de m\u00e1s equipos a las tropas como c\u00e1maras corporales para fortalecer las acciones en contra de los terroristas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno est\u00e1 ganando la Guerra contra las pandillas. En el cerco de seguridad montado en el municipio de Soyapango, las tropas est\u00e1n equipadas con modernos equipos tecnol\u00f3gicos para localizar y encontrar a los pandilleros que est\u00e1n acorralados en algunas colonias. Con el uso de drones, veh\u00edculos blindados de \u00faltima generaci\u00f3n equipados con modernos sistemas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13632,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[14,4],"tags":[],"class_list":{"0":"post-13631","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destacads","8":"category-elsalvador"},"jetpack_featured_media_url":"https:\/\/www.newsmillenium.com\/wp-content\/uploads\/2022\/12\/portada-1-fuerza-en-soyapango.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/13631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/comments?post=13631"}],"version-history":[{"count":1,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/13631\/revisions"}],"predecessor-version":[{"id":13633,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/posts\/13631\/revisions\/13633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media\/13632"}],"wp:attachment":[{"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/media?parent=13631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/categories?post=13631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.newsmillenium.com\/index.php\/wp-json\/wp\/v2\/tags?post=13631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}